{"id":453271,"date":"2026-05-13T00:06:13","date_gmt":"2026-05-13T05:06:13","guid":{"rendered":"https:\/\/arriendo.com\/co\/%es_type%\/medellin\/sabaneta\/\/"},"modified":"2026-05-13T00:06:13","modified_gmt":"2026-05-13T05:06:13","slug":"AR-453271","status":"publish","type":"properties","link":"https:\/\/arriendo.com\/co\/apartamentos\/medellin\/sabaneta\/AR-453271\/","title":{"rendered":"Apartamento para Venta y Arriendo en Sabaneta-Las Lomitas"},"content":{"rendered":"<p>Este espectacular apartamento de 88 M2 se encuentra en venta en la hermosa ciudad de Medell&iacute;n, ubicado en el departamento de Antioquia. Su &aacute;rea de terreno, construida y privada es exactamente la misma, ofreciendo un espacio amplio y c&oacute;modo para toda la familia. Cuenta con 3 alcobas muy bien distribuidas, las cuales ofrecen amplios armarios empotrados perfectos para organizar y almacenar tus pertenencias. Adem&aacute;s, el apartamento permite tener mascotas, convirti&eacute;ndolo en un hogar perfecto para aquellos amantes de los animales. La zona social de este apartamento es simplemente impresionante. Su balc&oacute;n te permitir&aacute; disfrutar de una vista panor&aacute;mica de la ciudad, mientras te relajas y disfrutas de un buen libro. Su barra estilo americano es perfecta para compartir con amigos y familiares mientras preparas deliciosas comidas en su moderna cocina integral. Sus 2 ba&ntilde;os son perfectos para el uso diario, con un ba&ntilde;o auxiliar para mayor comodidad y un ba&ntilde;o en la habitaci&oacute;n principal con detalles elegantes. El apartamento tambi&eacute;n cuenta con calentador, doble ventana para mayor aislamiento, y piso de cer&aacute;mica y m&aacute;rmol para un acabado de lujo. Entre sus caracter&iacute;sticas externas, este apartamento ofrece acceso pavimentado y se encuentra en una urbanizaci&oacute;n cerrada con vigilancia. Adem&aacute;s, cuenta con ascensor para mayor comodidad, parqueadero para visitantes y un garaje para tu veh&iacute;culo. El &aacute;rea social de la urbanizaci&oacute;n tambi&eacute;n es impresionante, con centros comerciales cercanos para tus compras, colegios y universidades para la educaci&oacute;n de tus hijos, y un gimnasio para mantener un estilo de vida saludable. Los parques cercanos, la piscina y el &aacute;rea de juego para ni&ntilde;os ofrecen un ambiente ideal para toda la familia. No tendr&aacute;s que preocuparte por la basura, ya que el apartamento cuenta con chute de basura y un sistema de recolecci&oacute;n eficiente. Y por si fuera poco, la ubicaci&oacute;n del apartamento cerca del transporte p&uacute;blico te permitir&aacute; moverte por la ciudad sin problema. No pierdas la oportunidad de vivir en este incre&iacute;ble apartamento, en una zona residencial rodeada de zonas verdes y deportivas, con canchas de baloncesto y f&uacute;tbol, perfectas para mantenerte activo y disfrutar del aire libre. Cont&aacute;ctanos ahora mismo para agendar una visita y haz realidad el sue&ntilde;o de tener un hogar en una de las ciudades m&aacute;s hermosas de Colombia.<\/p>\n","protected":false},"excerpt":{"rendered":"Este espectacular apartamento de 88 M2 se encuentra en venta...","protected":false},"author":5182,"featured_media":453273,"template":"","es_locations":[79,418,305],"es_categories":[124],"es_types":[114],"es_rent_periods":[],"es_labels":[],"es_statuses":[],"es_parkings":[],"es_roofs":[],"es_exterior_materials":[],"es_basements":[],"es_floor_coverings":[],"es_features":[],"es_amenities":[],"es_neighborhoods":[],"es_tags":[],"class_list":["post-453271","properties","type-properties","status-publish","has-post-thumbnail","hentry","es_location-antioquia","es_location-colombia","es_location-medellin","es_category-arriendo","es_type-apartamentos","es-post-entity"],"_links":{"self":[{"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/properties\/453271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/types\/properties"}],"author":[{"embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/users\/5182"}],"version-history":[{"count":1,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/properties\/453271\/revisions"}],"predecessor-version":[{"id":453272,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/properties\/453271\/revisions\/453272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/media\/453273"}],"wp:attachment":[{"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/media?parent=453271"}],"wp:term":[{"taxonomy":"es_location","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_locations?post=453271"},{"taxonomy":"es_category","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_categories?post=453271"},{"taxonomy":"es_type","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_types?post=453271"},{"taxonomy":"es_rent_period","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_rent_periods?post=453271"},{"taxonomy":"es_label","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_labels?post=453271"},{"taxonomy":"es_status","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_statuses?post=453271"},{"taxonomy":"es_parking","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_parkings?post=453271"},{"taxonomy":"es_roof","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_roofs?post=453271"},{"taxonomy":"es_exterior_material","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_exterior_materials?post=453271"},{"taxonomy":"es_basement","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_basements?post=453271"},{"taxonomy":"es_floor_covering","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_floor_coverings?post=453271"},{"taxonomy":"es_feature","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_features?post=453271"},{"taxonomy":"es_amenity","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_amenities?post=453271"},{"taxonomy":"es_neighborhood","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_neighborhoods?post=453271"},{"taxonomy":"es_tag","embeddable":true,"href":"https:\/\/arriendo.com\/co\/wp-json\/wp\/v2\/es_tags?post=453271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}